{"id":40482,"date":"2023-10-23T10:05:49","date_gmt":"2023-10-23T08:05:49","guid":{"rendered":"https:\/\/adc.cat\/?post_type=tribe_events&#038;p=40482"},"modified":"2023-10-24T13:58:16","modified_gmt":"2023-10-24T11:58:16","slug":"mission-diabetes-el-misterio-del-parque","status":"publish","type":"tribe_events","link":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/","title":{"rendered":"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb"},"content":{"rendered":"<p>[et_pb_section][et_pb_row][et_pb_column type=\u00bb4_4&#8243;][et_pb_text]<\/p>\n<div class=\"ou-description__content\">\n<div class=\"ou-description__description\">\n<p>En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios&#8230; Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos <img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f64c-1f3fc.svg\" alt=\"\ud83d\ude4c\ud83c\udffc\" \/> <strong>Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos a esta experiencia formativa! Aprende jugando! Abierto a todos los p\u00fablicos.<\/strong><\/p>\n<p><strong>Alguien nos ha robado la f\u00f3rmula y \u00a1necesitamos vuestra ayuda!<\/strong><\/p>\n<p><strong>\u00bfPodr\u00e9is superar todas las pruebas para preparar la f\u00f3rmula que ayudar\u00e1 en toda la poblaci\u00f3n con diabetes del mundo?<\/strong><\/p>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f468-200d-1f469-200d-1f467-200d-1f466.svg\" alt=\"\ud83d\udc68\u200d\ud83d\udc69\u200d\ud83d\udc67\u200d\ud83d\udc66\" \/> Actividad para resolver el enigma en familia o amistades.<br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/23f3.svg\" alt=\"\u23f3\" \/> M\u00e1s de 8 pruebas para resolver antes de que se agote el tiempo.<br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f60b.svg\" alt=\"\ud83d\ude0b\" \/> Demuestra todo el que sabes de la diabetes jugando.<br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f499.svg\" alt=\"\ud83d\udc99\" \/> Ven a celebrar el D\u00eda Mundial de la Diabetes resolviendo\u00a0enigmas y superando retos.<br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f469-1f3fd-200d-1f3a8.svg\" alt=\"\ud83d\udc69\ud83c\udffd\u200d\ud83c\udfa8\" \/> Pintura, movimiento y mucha diversi\u00f3n.<\/p>\n<p><strong>Inscr\u00edbete ahora y prep\u00e1rate para descifrar el misterio de la diabetes en un entorno lleno de diversi\u00f3n y aprendizaje. Esperamos verte aqu\u00ed!<\/strong><\/p>\n<\/div>\n<\/div>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f4cd.svg\" alt=\"\ud83d\udccd\" \/> <strong>\u00bfD\u00f3nde quedamos?<\/strong> Junto a la escultura de \u00bb La Mujer\u00a0 y el p\u00e1jaro\u00bb al Parque Joan Mir\u00f3 de Barcelona. Com arribar?: <a href=\"https:\/\/goo.gl\/maps\/2JpzuFiQ9DeXPK5p9\">https:\/\/maps.app.goo.gl\/fYCAgHytbQGs4aQH8<\/a><br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f5d3.svg\" alt=\"\ud83d\uddd3\ufe0f\" \/> <strong>Fecha<\/strong>: S\u00e1bado 11 de noviembre<br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f556.svg\" alt=\"\ud83d\udd56\" \/> <strong>Hora<\/strong>: a las 10.30 horas.<br \/>\n<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f9fa.svg\" alt=\"\ud83e\uddfa\" \/><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/26f9-1f3fb-200d-2640-fe0f.svg\" alt=\"\u26f9\ud83c\udffb\u200d\u2640\ufe0f\" \/> <strong>Qu\u00e9 hay que llevar:<\/strong> Agua, ropa c\u00f3moda \u00a1y diversi\u00f3n!<br \/>\n<strong>\ud83d\udde3\ufe0f Organizado por<\/strong>: Servicios Centrales de la ADC.<\/p>\n<p><span class=\"d2edcug0 hpfvmrgz qv66sw1b c1et5uql lr9zc1uh a8c37x1j fe6kdd0r mau55g9w c8b282yb keod5gw0 nxhoafnm aigsh9s9 d3f4x2em iv3no6db jq4qci2q a3bd9o3v b1v8xokw oo9gr5id hzawbc8m\" dir=\"auto\"><span class=\"x193iq5w xeuugli x13faqbe x1vvkbs x1xmvt09 x1lliihq x1s928wv xhkezso x1gmr53x x1cpjm7i x1fgarty x1943h6x xudqn12 x3x7a5m x6prxxf xvq8zen xo1l8bm xzsf02u x1yc453h\" dir=\"auto\">Actividad obierta a todo el mundo<\/span>.<\/span><\/p>\n<p style=\"text-align: center;\"><a href='https:\/\/adc.playoffinformatica.com\/activitat\/325\/Missio-Diabetil:-el-Misteri-del-Parc\/' class='big-button bigblue' target=\"_blank\">Inscripci\u00f3n<\/a><\/p>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/26a0.svg\" alt=\"\u26a0\ufe0f\" \/> Reg\u00edstrate al acontecimiento proporcionando el nombre y apellido del adulto responsable del grupo y el n\u00famero de acompa\u00f1antes (m\u00ednimo una persona y m\u00e1ximo un grupo de 6 personas).<\/p>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f4f2.svg\" alt=\"\ud83d\udcf2\" \/> Aseg\u00farate de tener un m\u00f3vil activo para posibles comunicaciones antes o durante el juego.<\/p>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/2764.svg\" alt=\"\u2764\ufe0f\" \/>\u200d Ten en cuenta que esta actividad se realizar\u00e1 al aire libre en el Parque de Joan Mir\u00f3. En caso de condiciones clim\u00e1ticas adversas u otras circunstancias imprevistas, te informaremos con antelaci\u00f3n sobre cualquier cambio en la programaci\u00f3n.<\/p>\n<p><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f499.svg\" alt=\"\ud83d\udc99\" \/> \u00a1An\u00edmate a venir! Si no tienes grupo, \u00a1all\u00e1 lo crearemos!<\/p>\n<p>&nbsp;<\/p>\n<p>M\u00e1s informaci\u00f3n <span class=\"fe5nidar khvhiq1o r5qsrrlp i5tg98hk f9ovudaz przvwfww gx1rr48f gfz4du6o r7fjleex nz2484kf svot0ezm dcnh1tix sxl192xd t3g6t33p\"><span class=\"mpj7bzys xzlurrtv\">\ud83d\udce9<\/span><\/span> <a href=\"mailto:adcgirona@adc.cat\">adc@adc.cat<\/a>. <span class=\"fe5nidar khvhiq1o r5qsrrlp i5tg98hk f9ovudaz przvwfww gx1rr48f gfz4du6o r7fjleex nz2484kf svot0ezm dcnh1tix sxl192xd t3g6t33p\"><span class=\"mpj7bzys xzlurrtv\">\ud83d\udcde<\/span><\/span>Tel. 934513406.<\/p>\n<p>\u00a1Con muchas ganas de celebrar este d\u00eda contigo!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios&#8230; Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos  Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.<\/p>\n<p>Alguien nos ha robado la f\u00f3rmula y \u00a1necesitamos vuestra ayuda!<\/p>\n","protected":false},"author":2,"featured_media":40493,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[69,98],"class_list":["post-40482","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-barcelona-es","tribe_events_cat-dia-mundial-de-la-diabetes","cat_barcelona-es","cat_dia-mundial-de-la-diabetes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya<\/title>\n<meta name=\"description\" content=\"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y necesitamos vuestra ayuda!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya\" \/>\n<meta property=\"og:description\" content=\"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y \u00a1necesitamos vuestra ayuda!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/\" \/>\n<meta property=\"og:site_name\" content=\"ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ADC.CAT\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T11:58:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1820\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya\" \/>\n<meta name=\"twitter:description\" content=\"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y \u00a1necesitamos vuestra ayuda!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@ADC_CAT\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/\",\"url\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/\",\"name\":\"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adc.cat\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CARTELL-4-cast.jpg\",\"datePublished\":\"2023-10-23T08:05:49+00:00\",\"dateModified\":\"2023-10-24T11:58:16+00:00\",\"description\":\"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y necesitamos vuestra ayuda!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adc.cat\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CARTELL-4-cast.jpg\",\"contentUrl\":\"https:\\\/\\\/adc.cat\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CARTELL-4-cast.jpg\",\"width\":1820,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitat\\\/mission-diabetes-el-misterio-del-parque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/adc.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/adc.cat\\\/es\\\/activitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/adc.cat\\\/es\\\/\",\"name\":\"ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya\",\"description\":\"L&#039;ADC representa els pacients amb diabetis de Catalunya. Els nostres objectius: informar, aconsellar, ajudar i defensar les persones amb diabetis i promoure la sensibilitzaci\u00f3 de la resta de la societat\",\"publisher\":{\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adc.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/#organization\",\"name\":\"Associaci\u00f3 de Diabetis de Catalunya\",\"url\":\"https:\\\/\\\/adc.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adc.cat\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/associacio_de_diabetis_catalunya.png\",\"contentUrl\":\"https:\\\/\\\/adc.cat\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/associacio_de_diabetis_catalunya.png\",\"width\":512,\"height\":239,\"caption\":\"Associaci\u00f3 de Diabetis de Catalunya\"},\"image\":{\"@id\":\"https:\\\/\\\/adc.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ADC.CAT\\\/\",\"https:\\\/\\\/x.com\\\/ADC_CAT\",\"https:\\\/\\\/www.instagram.com\\\/adc_cat\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/associacio-de-diabetis-de-catalunya\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7BiJMxG_5sHYUhMAlevAWA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya","description":"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y necesitamos vuestra ayuda!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/","og_locale":"es_ES","og_type":"article","og_title":"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya","og_description":"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y \u00a1necesitamos vuestra ayuda!","og_url":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/","og_site_name":"ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya","article_publisher":"https:\/\/www.facebook.com\/ADC.CAT\/","article_modified_time":"2023-10-24T11:58:16+00:00","og_image":[{"width":1820,"height":960,"url":"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya","twitter_description":"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y \u00a1necesitamos vuestra ayuda!","twitter_image":"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg","twitter_site":"@ADC_CAT","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/","url":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/","name":"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb - ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya","isPartOf":{"@id":"https:\/\/adc.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/#primaryimage"},"image":{"@id":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/#primaryimage"},"thumbnailUrl":"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg","datePublished":"2023-10-23T08:05:49+00:00","dateModified":"2023-10-24T11:58:16+00:00","description":"En el ADC hemos recibido un aviso que la f\u00f3rmula de la insulina ha desaparecido de todos los laboratorios... Ven al Parque de Joan Mir\u00f3 el s\u00e1bado 11 de noviembre para resolver las pruebas y ayudar a recuperarla! Entre todas las personas seguro que lo conseguimos Ven a disfrutar de la Misi\u00f3n Diabetes e invita a tu familia y amigos! Abierto a todos los p\u00fablicos.Alguien nos ha robado la f\u00f3rmula y necesitamos vuestra ayuda!","breadcrumb":{"@id":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/#primaryimage","url":"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg","contentUrl":"https:\/\/adc.cat\/wp-content\/uploads\/2023\/10\/CARTELL-4-cast.jpg","width":1820,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/adc.cat\/es\/activitat\/mission-diabetes-el-misterio-del-parque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/adc.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/adc.cat\/es\/activitats\/"},{"@type":"ListItem","position":3,"name":"\ud83d\udc69\ud83c\udffc\u200d\ud83d\udd2c\ud83d\udc40 Missi\u00f3n Diabetes: el Misterio del Parque \ud83c\udfa8\ud83d\udd75\ud83c\udffb"}]},{"@type":"WebSite","@id":"https:\/\/adc.cat\/es\/#website","url":"https:\/\/adc.cat\/es\/","name":"ADC \u2013 Associaci\u00f3 de Diabetis de Catalunya","description":"L&#039;ADC representa els pacients amb diabetis de Catalunya. Els nostres objectius: informar, aconsellar, ajudar i defensar les persones amb diabetis i promoure la sensibilitzaci\u00f3 de la resta de la societat","publisher":{"@id":"https:\/\/adc.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adc.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adc.cat\/es\/#organization","name":"Associaci\u00f3 de Diabetis de Catalunya","url":"https:\/\/adc.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adc.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/adc.cat\/wp-content\/uploads\/2022\/01\/associacio_de_diabetis_catalunya.png","contentUrl":"https:\/\/adc.cat\/wp-content\/uploads\/2022\/01\/associacio_de_diabetis_catalunya.png","width":512,"height":239,"caption":"Associaci\u00f3 de Diabetis de Catalunya"},"image":{"@id":"https:\/\/adc.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ADC.CAT\/","https:\/\/x.com\/ADC_CAT","https:\/\/www.instagram.com\/adc_cat\/","https:\/\/www.linkedin.com\/company\/associacio-de-diabetis-de-catalunya","https:\/\/www.youtube.com\/channel\/UC7BiJMxG_5sHYUhMAlevAWA"]}]}},"_links":{"self":[{"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/tribe_events\/40482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":9,"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/tribe_events\/40482\/revisions"}],"predecessor-version":[{"id":40585,"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/tribe_events\/40482\/revisions\/40585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/media\/40493"}],"wp:attachment":[{"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/media?parent=40482"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/tags?post=40482"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/adc.cat\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=40482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}